{"id":3876,"date":"2024-11-28T15:11:53","date_gmt":"2024-11-28T15:11:53","guid":{"rendered":"http:\/\/condisystems.com\/?page_id=3876"},"modified":"2025-08-28T13:50:21","modified_gmt":"2025-08-28T13:50:21","slug":"about-us","status":"publish","type":"page","link":"https:\/\/condisystems.com\/en\/about-us","title":{"rendered":"About us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3876\" class=\"elementor elementor-3876\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-522fbb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"522fbb1\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e361416\" data-id=\"e361416\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0afa7e4 elementor-widget elementor-widget-spacer\" data-id=\"0afa7e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a366f2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a366f2c\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc0318c\" data-id=\"cc0318c\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08ed5e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08ed5e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e19eeea w-xl-41 mb-4 mb-lg-0\" data-id=\"e19eeea\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95140a7 mb-4 pb-3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"95140a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Leidenschaft f\u00fcr hochwertige Konditionierl\u00f6sungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9f2972 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f9f2972\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:1200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"283\" data-end=\"426\"><strong data-start=\"283\" data-end=\"299\">Condisystems<\/strong> \u2013 eine Marke der IMA Buscher GmbH \u2013 steht seit 2006 f\u00fcr Qualit\u00e4t, Innovation und Effizienz in der Kunststoffkonditionierung.<\/p><p data-start=\"428\" data-end=\"824\">Als inhabergef\u00fchrtes Familienunternehmen mit Sitz in der Pfalz kombinieren wir regionale Fertigung mit internationalem Anspruch. Heute vertrauen Kunden aus \u00fcber 40 L\u00e4ndern auf unsere Systeme, die f\u00fcr ihre Zuverl\u00e4ssigkeit, Langlebigkeit und Energieeffizienz bekannt sind. Unser Ziel ist es, Unternehmen weltweit mit Konditionieranlagen auszustatten, die Prozesse stabilisieren und Kosten senken.<\/p><p data-start=\"826\" data-end=\"1172\">Unser Portfolio deckt die gesamte Bandbreite moderner Verfahren ab: von der klassischen <strong data-start=\"914\" data-end=\"938\">Dampfkonditionierung<\/strong> \u00fcber pr\u00e4zise <strong data-start=\"952\" data-end=\"977\">Vakuumkonditionierung<\/strong> bis hin zur innovativen <strong data-start=\"1002\" data-end=\"1031\">No-Energy-Konditionierung<\/strong>. Damit bieten wir f\u00fcr jede Anforderung \u2013 vom kompakten <strong>Konditionierschrank<\/strong> bis zum gro\u00dfvolumigen <strong>Konditioniercontainer<\/strong> \u2013 die optimale L\u00f6sung.<\/p><p data-start=\"1174\" data-end=\"1512\">Besonderen Wert legen wir auf Langlebigkeit, Wartungsfreundlichkeit und gleichbleibende Qualit\u00e4t. Unsere Anlagen sind darauf ausgelegt, \u00fcber viele Jahre im industriellen Dauereinsatz zuverl\u00e4ssig zu arbeiten. Zugleich entwickeln wir kontinuierlich neue Technologien, um die Konditionierung noch effizienter und nachhaltiger zu gestalten.<\/p><p data-start=\"1514\" data-end=\"1830\">Mit mehr als zwei Jahrzehnten Erfahrung, einem starken Fokus auf Nachhaltigkeit und dem weltweit breitesten Produktportfolio sind wir der ideale Partner, um die Konditionierung Ihrer Bauteile auf das n\u00e4chste Level zu heben. Gemeinsam mit Ihnen entwickeln wir L\u00f6sungen, die langfristige Wettbewerbsvorteile sichern.<\/p><p data-start=\"1832\" data-end=\"1881\"><strong data-start=\"1832\" data-end=\"1879\">Condisystems \u2013 powered by IMA Buscher GmbH.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c20da65 ms-xl-auto\" data-id=\"c20da65\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a516c0 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-porto_steps\" data-id=\"9a516c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"porto_steps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"timeline\"><div class=\"timeline-body\"><div class=\"timeline-date\"><h3 class=\"time-text step-item-subtitle\">Historie<\/h3><\/div><article class=\"timeline-box left\"><div><h4 class=\"timeline-item-title step-item-title\">1996 - Erste Erfahrungen <\/h4><div class=\"timeline-item-content\"><p>Beginn der Entwicklung von Verfahren zur gezielten Feuchtigkeitsaufnahme bei Polyamid.<\/p><\/div><\/div><\/article><article class=\"timeline-box right\"><div><h4 class=\"timeline-item-title step-item-title\">2006 - Gr\u00fcndung IMA Buscher GmbH<\/h4><div class=\"timeline-item-content\"><p>Start mit Fokus auf Konditionieranlagen, regionale Fertigung, globale Vision.<\/p><\/div><\/div><\/article><article class=\"timeline-box left\"><div><h4 class=\"timeline-item-title step-item-title\">2011 - Innovation: No-Energy<\/h4><div class=\"timeline-item-content\"><p>Markteinf\u00fchrung der energieeffizienten, energielosen Konditionierung.<\/p><\/div><\/div><\/article><article class=\"timeline-box right\"><div><h4 class=\"timeline-item-title step-item-title\">2014 - Ausbau des Portfolios<\/h4><div class=\"timeline-item-content\"><p>Entwicklung neuer Konditionierkammern und automatisierter Anlagen.<\/p><\/div><\/div><\/article><article class=\"timeline-box left\"><div><h4 class=\"timeline-item-title step-item-title\">2024 - Konditioniercontainer<\/h4><div class=\"timeline-item-content\"><p>Aufnahme von 5-, 10-, 20- und <br \/>40-Fu\u00df-Konditioniercontainern ins Produktportfolio.<\/p><\/div><\/div><\/article><article class=\"timeline-box right\"><div><h4 class=\"timeline-item-title step-item-title\">Heute - Condisystems<\/h4><div class=\"timeline-item-content\"><p>Aufbau der eigenen Marke \u2013 weltweit breitestes Portfolio an Konditionieranlagen, von kompakten Schr\u00e4nken bis zu Gro\u00dfkammern.<\/p><\/div><\/div><\/article><\/div><\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t<div class=\"elementor-element elementor-element-917698d e-flex e-con-boxed e-con e-parent\" data-id=\"917698d\" data-element_type=\"container\" data-e-type=\"container\">\r\n\t\t\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-4adb78c elementor-widget elementor-widget-heading\" data-id=\"4adb78c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Das macht uns aus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fcc878 my-5 py-4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fcc878\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b825c1e\" data-id=\"b825c1e\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3faf29 h-100 custom-box-shadow-1 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a3faf29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"404\" height=\"216\" src=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7.jpg\" class=\"attachment-full size-full wp-image-3881\" alt=\"\" srcset=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7.jpg 404w, https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7-400x214.jpg 400w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Gr\u00fcndung<\/h3><p class=\"elementor-image-box-description\"><span class=\"custom-font1\" style=\"font-size: 1.2em;line-height: 1.4\">Mehr als ein Jahrzehnt Erfahrung f\u00fcr Ihren Erfolg<\/span><br><br>Gesch\u00e4ftsf\u00fchrer Edmund Buscher, seit 1996 in der Branche t\u00e4tig, gr\u00fcndete das Unternehmen im Jahr 2006 mit Fokus auf Qualit\u00e4t, Innovation und Kundenzufriedenheit auf.\n<br><br>\nHeute bietet die IMA Buscher GmbH ma\u00dfgeschneiderte L\u00f6sungen und ein breites Portfolio an Konditionieranlagen, die f\u00fcr ihre Langlebigkeit und hohe Fertigungsstandards bekannt sind.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6965dff\" data-id=\"6965dff\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8b8f72 h-100 custom-box-shadow-1 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"d8b8f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"404\" height=\"216\" src=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-8.jpg\" class=\"attachment-full size-full wp-image-3882\" alt=\"\" srcset=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-8.jpg 404w, https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-8-400x214.jpg 400w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">unsere Mission<\/h3><p class=\"elementor-image-box-description\"><span class=\"custom-font1\" style=\"font-size: 1.2em;line-height: 1.4\">Die Kunststoffindustrie mit modernster Konditioniertechnik auf ein neues Level zu heben.<\/span><br><br> Mit innovativen Technologien und nachhaltigen Ans\u00e4tzen erm\u00f6glichen wir unseren Kunden, ihre Produktionsprozesse zu optimieren und gleichzeitig Ressourcen zu schonen.\n<br><br>\nGemeinsam mit unseren Partnern schaffen wir die Basis f\u00fcr eine zukunftssichere Fertigung. Unsere L\u00f6sungen erf\u00fcllen h\u00f6chste Anforderungen an Verl\u00e4sslichkeit und Pr\u00e4zision und setzen neue Ma\u00dfst\u00e4be in der Branche.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5e6bc11 mx-md-auto mx-lg-0\" data-id=\"5e6bc11\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91dbbb3 h-100 custom-box-shadow-1 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"91dbbb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"http:\/\/condisystems.com\/konditionieranlagen\" tabindex=\"-1\"><img decoding=\"async\" width=\"404\" height=\"216\" src=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-9.jpg\" class=\"attachment-full size-full wp-image-3883\" alt=\"\" srcset=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-9.jpg 404w, https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-9-400x214.jpg 400w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"http:\/\/condisystems.com\/konditionieranlagen\">Portfolio<\/a><\/h3><p class=\"elementor-image-box-description\"><span class=\"custom-font1\" style=\"font-size: 1.2em;line-height: 1.4\">Von kompakten Schr\u00e4nken bis hin zu Gro\u00dfkammern und Konditioniercontainern bieten wir das weltweit breiteste Portfolio an Konditionieranlagen.<\/span><br><br>\nUnsere L\u00f6sungen decken jedes Verfahren ab \u2013 von energieeffizienter No-Energy-Technik \u00fcber Sattdampf bis hin zu pr\u00e4ziser Vakuumkonditionierung.\nDamit stellen wir sicher, dass Sie f\u00fcr jede Anwendung die passende, langlebige und effiziente L\u00f6sung erhalten.\n<br><br>\n<a>Zu den Anlagen <i class=\"fas fa-long-arrow-alt-right ms-2\"><\/i><\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a33a10 custom-overlay-dark p-t-xl elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a33a10\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0593418 pt-5 pb-3\" data-id=\"0593418\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1970204 font-style-normal pb-3 mb-5 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1970204\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unser Erfolg in Zahlen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3610482 mb-4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3610482\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Mit \u00fcber zwei Jahrzehnten Erfahrung in der Entwicklung und Fertigung von Konditionieranlagen haben wir den Markt f\u00fcr Kunststoffkonditionierung nachhaltig gepr\u00e4gt. Durch unsere innovativen Verfahren \u2013 von energieeffizienter Dampfkonditionierung \u00fcber pr\u00e4zise Vakuumtechnik bis hin zu einzigartigen No-Energy-L\u00f6sungen \u2013 erzielen unsere Anlagen messbare Ergebnisse, die Produktionsprozesse weltweit verbessern und Qualit\u00e4tsstandards sichern.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-f98787a m-t-sm elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f98787a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:700}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-09f5a58\" data-id=\"09f5a58\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29719db elementor-widget elementor-widget-porto_stat_counter\" data-id=\"29719db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"porto_stat_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"stats-block stats-top\"><div class=\"stats-desc\"><div id=\"counter_13151671316a03c1958a72f\" data-id=\"counter_13151671316a03c1958a72f\" class=\"stats-number\" style=\" \" data-speed=\"3\" data-counter-value=\"20\" data-separator=\",\" data-decimal=\".\">0<\/div><div class=\"counter_suffix mycust\" style=\" \">+<\/div><div class=\"stats-text\" style=\"\">Jahre Erfahrung<\/div><\/div><\/div><script>\r\n\t( function() {\r\n\t\tvar porto_inc_counter_js = function() {\r\n\t\t\t( function( $ ) {\r\n\t\t\t\tif (typeof countUp == \"undefined\") {\r\n\t\t\t\t\tvar c = document.createElement(\"script\");\r\n\t\t\t\t\tc.src = \"https:\/\/condisystems.com\/wp-content\/plugins\/porto-functionality\/shortcodes\/assets\/js\/countup.min.js\";\r\n\t\t\t\t\tif (!$('script[src=\"' + c.src + '\"]').length) {\r\n\t\t\t\t\t\tdocument.getElementsByTagName(\"body\")[0].appendChild(c);\r\n\t\t\t\t\t}\r\n\t\t\t\t\tc = document.createElement(\"script\");\r\n\t\t\t\t\tc.src = \"https:\/\/condisystems.com\/wp-content\/plugins\/porto-functionality\/shortcodes\/assets\/js\/countup-loader.min.js\";\r\n\t\t\t\t\tif (!$('script[src=\"' + c.src + '\"]').length) {\r\n\t\t\t\t\t\tdocument.getElementsByTagName(\"body\")[0].appendChild(c);\r\n\t\t\t\t\t}\r\n\t\t\t\t}\r\n\t\t\t} )( jQuery );\r\n\t\t};\r\n\r\n\t\tif ( window.theme && theme.isLoaded ) {\r\n\t\t\tporto_inc_counter_js();\r\n\t\t} else {\r\n\t\t\twindow.addEventListener( 'load', porto_inc_counter_js );\r\n\t\t}\r\n\t} )();\r\n<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ba725a elementor-widget elementor-widget-text-editor\" data-id=\"8ba725a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Know-how in Entwicklung &amp; Fertigung von Konditionieranlagen<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-399c0c3\" data-id=\"399c0c3\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca7445b elementor-widget elementor-widget-porto_stat_counter\" data-id=\"ca7445b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"porto_stat_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"stats-block stats-top\"><div class=\"stats-desc\"><div id=\"counter_18188950406a03c1958ae59\" data-id=\"counter_18188950406a03c1958ae59\" class=\"stats-number\" style=\" \" data-speed=\"3\" data-counter-value=\"200\" data-separator=\",\" data-decimal=\".\">0<\/div><div class=\"counter_suffix mycust\" style=\" \">+<\/div><div class=\"stats-text\" style=\"\">Anlagen auf dem Markt<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90a8feb elementor-widget elementor-widget-text-editor\" data-id=\"90a8feb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Von Europa bis Asien &#8211; Vertrauen auf unsere L\u00f6sungen<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bc2a509\" data-id=\"bc2a509\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-767ad20 elementor-widget elementor-widget-porto_stat_counter\" data-id=\"767ad20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"porto_stat_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"stats-block stats-top\"><div class=\"stats-desc\"><div id=\"counter_5463086706a03c1958b559\" data-id=\"counter_5463086706a03c1958b559\" class=\"stats-number\" style=\" \" data-speed=\"3\" data-counter-value=\"3\" data-separator=\",\" data-decimal=\".\">0<\/div><div class=\"counter_suffix mycust\" style=\" \">Mrd. +<\/div><div class=\"stats-text\" style=\"\">Konditionierte Polyamidartikel<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a76992f elementor-widget elementor-widget-text-editor\" data-id=\"a76992f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Qualit\u00e4t, auf die weltweit f\u00fchrende Hersteller setzen<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-013fcb9\" data-id=\"013fcb9\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-562bc64 elementor-widget elementor-widget-porto_stat_counter\" data-id=\"562bc64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"porto_stat_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"stats-block stats-top\"><div class=\"stats-desc\"><div id=\"counter_18481064786a03c1958bb8d\" data-id=\"counter_18481064786a03c1958bb8d\" class=\"stats-number\" style=\" \" data-speed=\"3\" data-counter-value=\"20\" data-separator=\",\" data-decimal=\".\">0<\/div><div class=\"counter_suffix mycust\" style=\" \">+<\/div><div class=\"stats-text\" style=\"\">verschiedene Anlagen im Portfolio<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fdaacb elementor-widget elementor-widget-text-editor\" data-id=\"2fdaacb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Von kompakten Schr\u00e4nken bis zu 40 Fu\u00df Konditioniercontainern<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17eec17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17eec17\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa3c938\" data-id=\"aa3c938\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adc54d6 elementor-widget elementor-widget-spacer\" data-id=\"adc54d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32959343 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32959343\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-336e9b0\" data-id=\"336e9b0\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24f8d4b1 elementor-widget elementor-widget-heading\" data-id=\"24f8d4b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ihre Ansprechpartner<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86515f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86515f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a5b4d0a\" data-id=\"6a5b4d0a\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dd6561e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3dd6561e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"273\" src=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/12\/Coming-soon.jpg\" class=\"attachment-full size-full wp-image-4125\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Edmund Buscher<\/h3><p class=\"elementor-image-box-description\">Gesch\u00e4ftsf\u00fchrer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19542a1 elementor-widget elementor-widget-text-editor\" data-id=\"19542a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E-Mail: buscher.e@ima-buscher.de<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-225b8f9c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"225b8f9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-26c11fa9\" data-id=\"26c11fa9\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58a0352d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"58a0352d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"273\" src=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/12\/Coming-soon.jpg\" class=\"attachment-full size-full wp-image-4125\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Monika Buscher<\/h3><p class=\"elementor-image-box-description\">Buchhaltung<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37dfea0 elementor-widget elementor-widget-text-editor\" data-id=\"37dfea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">E-Mail: buscher.m@ima-buscher.de<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb1c8b2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3fb1c8b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3a47f5e8\" data-id=\"3a47f5e8\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fd8f199 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1fd8f199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"273\" src=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/12\/Coming-soon.jpg\" class=\"attachment-full size-full wp-image-4125\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Marc Buscher<\/h3><p class=\"elementor-image-box-description\">Vertrieb<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c93dd elementor-widget elementor-widget-text-editor\" data-id=\"f6c93dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E-Mail: busche.marc@ima-buscher.de<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae7ed87 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3ae7ed87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t<div class=\"elementor-element elementor-element-609630d e-flex e-con-boxed e-con e-parent\" data-id=\"609630d\" data-element_type=\"container\" data-e-type=\"container\">\r\n\t\t\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Unsere Leidenschaft f\u00fcr hochwertige Konditionierl\u00f6sungen Condisystems \u2013 eine Marke der IMA Buscher GmbH \u2013 steht seit 2006 f\u00fcr Qualit\u00e4t, Innovation und Effizienz in der Kunststoffkonditionierung. Als inhabergef\u00fchrtes Familienunternehmen mit Sitz in der Pfalz kombinieren wir regionale Fertigung mit internationalem Anspruch. Heute vertrauen Kunden aus \u00fcber 40 L\u00e4ndern auf unsere Systeme, die f\u00fcr ihre Zuverl\u00e4ssigkeit, Langlebigkeit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3876","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcber Condisystems \u2013 Spezialist f\u00fcr Konditionieranlagen seit 2006<\/title>\n<meta name=\"description\" content=\"Konditionieranlagen von Condisystems: Familienunternehmen aus der Pfalz mit 25 Jahren Erfahrung. Prozesssichere und langlebige L\u00f6sungen f\u00fcr PA6\/PA66.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/condisystems.com\/en\/about-us\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber Condisystems \u2013 Spezialist f\u00fcr Konditionieranlagen seit 2006\" \/>\n<meta property=\"og:description\" content=\"Konditionieranlagen von Condisystems: Familienunternehmen aus der Pfalz mit 25 Jahren Erfahrung. Prozesssichere und langlebige L\u00f6sungen f\u00fcr PA6\/PA66.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/condisystems.com\/en\/about-us\" \/>\n<meta property=\"og:site_name\" content=\"Condisystems\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T13:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"404\" \/>\n\t<meta property=\"og:image:height\" content=\"216\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/condisystems.com\\\/ueber-uns\",\"url\":\"https:\\\/\\\/condisystems.com\\\/ueber-uns\",\"name\":\"\u00dcber Condisystems \u2013 Spezialist f\u00fcr Konditionieranlagen seit 2006\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/condisystems.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/condisystems.com\\\/ueber-uns#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/condisystems.com\\\/ueber-uns#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/condisystems.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/it-generic-7.jpg\",\"datePublished\":\"2024-11-28T15:11:53+00:00\",\"dateModified\":\"2025-08-28T13:50:21+00:00\",\"description\":\"Konditionieranlagen von Condisystems: Familienunternehmen aus der Pfalz mit 25 Jahren Erfahrung. Prozesssichere und langlebige L\u00f6sungen f\u00fcr PA6\\\/PA66.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/condisystems.com\\\/ueber-uns#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/condisystems.com\\\/ueber-uns\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/condisystems.com\\\/ueber-uns#primaryimage\",\"url\":\"https:\\\/\\\/condisystems.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/it-generic-7.jpg\",\"contentUrl\":\"https:\\\/\\\/condisystems.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/it-generic-7.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/condisystems.com\\\/ueber-uns#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/condisystems.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/condisystems.com\\\/#website\",\"url\":\"https:\\\/\\\/condisystems.com\\\/\",\"name\":\"Condisystems\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/condisystems.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/condisystems.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/condisystems.com\\\/#organization\",\"name\":\"IMA-Buscher GmbH\",\"url\":\"https:\\\/\\\/condisystems.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/condisystems.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/condisystems.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-android-chrome-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/condisystems.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-android-chrome-512x512-1.png\",\"width\":512,\"height\":512,\"caption\":\"IMA-Buscher GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/condisystems.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Condisystems - Specialising in conditioning systems since 2006","description":"Conditioning systems from Condisystems: family-run company from the Palatinate with 25 years of experience. Reliable and durable solutions for PA6\/PA66.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/condisystems.com\/en\/about-us","og_locale":"en_GB","og_type":"article","og_title":"\u00dcber Condisystems \u2013 Spezialist f\u00fcr Konditionieranlagen seit 2006","og_description":"Konditionieranlagen von Condisystems: Familienunternehmen aus der Pfalz mit 25 Jahren Erfahrung. Prozesssichere und langlebige L\u00f6sungen f\u00fcr PA6\/PA66.","og_url":"https:\/\/condisystems.com\/en\/about-us","og_site_name":"Condisystems","article_modified_time":"2025-08-28T13:50:21+00:00","og_image":[{"width":404,"height":216,"url":"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/condisystems.com\/ueber-uns","url":"https:\/\/condisystems.com\/ueber-uns","name":"About Condisystems - Specialising in conditioning systems since 2006","isPartOf":{"@id":"https:\/\/condisystems.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/condisystems.com\/ueber-uns#primaryimage"},"image":{"@id":"https:\/\/condisystems.com\/ueber-uns#primaryimage"},"thumbnailUrl":"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7.jpg","datePublished":"2024-11-28T15:11:53+00:00","dateModified":"2025-08-28T13:50:21+00:00","description":"Conditioning systems from Condisystems: family-run company from the Palatinate with 25 years of experience. Reliable and durable solutions for PA6\/PA66.","breadcrumb":{"@id":"https:\/\/condisystems.com\/ueber-uns#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/condisystems.com\/ueber-uns"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/condisystems.com\/ueber-uns#primaryimage","url":"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7.jpg","contentUrl":"https:\/\/condisystems.com\/wp-content\/uploads\/2024\/11\/it-generic-7.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/condisystems.com\/ueber-uns#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/condisystems.com\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"WebSite","@id":"https:\/\/condisystems.com\/#website","url":"https:\/\/condisystems.com\/","name":"Condisystems","description":"","publisher":{"@id":"https:\/\/condisystems.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/condisystems.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/condisystems.com\/#organization","name":"IMA-Buscher GmbH","url":"https:\/\/condisystems.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/condisystems.com\/#\/schema\/logo\/image\/","url":"https:\/\/condisystems.com\/wp-content\/uploads\/2025\/08\/cropped-android-chrome-512x512-1.png","contentUrl":"https:\/\/condisystems.com\/wp-content\/uploads\/2025\/08\/cropped-android-chrome-512x512-1.png","width":512,"height":512,"caption":"IMA-Buscher GmbH"},"image":{"@id":"https:\/\/condisystems.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/pages\/3876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/comments?post=3876"}],"version-history":[{"count":160,"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/pages\/3876\/revisions"}],"predecessor-version":[{"id":5920,"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/pages\/3876\/revisions\/5920"}],"wp:attachment":[{"href":"https:\/\/condisystems.com\/en\/wp-json\/wp\/v2\/media?parent=3876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}